{"id":53,"count":2,"description":"","link":"https:\/\/class.one\/zh-hans\/course-tag\/malay\/","name":"Malay","slug":"malay","taxonomy":"course-tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Malay Archives - Class One<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/class.one\/course-tag\/malay\/\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Malay Archives - Class One\" \/>\n<meta property=\"og:url\" content=\"https:\/\/class.one\/course-tag\/malay\/\" \/>\n<meta property=\"og:site_name\" content=\"Class One\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/class.one\/course-tag\/malay\/\",\"url\":\"https:\/\/class.one\/course-tag\/malay\/\",\"name\":\"Malay Archives - Class One\",\"isPartOf\":{\"@id\":\"https:\/\/class.one\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/class.one\/course-tag\/malay\/#breadcrumb\"},\"inLanguage\":\"zh-CN\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/class.one\/course-tag\/malay\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/class.one\/zh-hans\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Malay\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/class.one\/#website\",\"url\":\"https:\/\/class.one\/\",\"name\":\"Class One\",\"description\":\"Online Learning Platform in Malaysia\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/class.one\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-CN\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Malay Archives - Class One","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/class.one\/course-tag\/malay\/","og_locale":"zh_CN","og_type":"article","og_title":"Malay Archives - Class One","og_url":"https:\/\/class.one\/course-tag\/malay\/","og_site_name":"Class One","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/class.one\/course-tag\/malay\/","url":"https:\/\/class.one\/course-tag\/malay\/","name":"Malay Archives - Class One","isPartOf":{"@id":"https:\/\/class.one\/#website"},"breadcrumb":{"@id":"https:\/\/class.one\/course-tag\/malay\/#breadcrumb"},"inLanguage":"zh-CN"},{"@type":"BreadcrumbList","@id":"https:\/\/class.one\/course-tag\/malay\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/class.one\/zh-hans\/"},{"@type":"ListItem","position":2,"name":"Malay"}]},{"@type":"WebSite","@id":"https:\/\/class.one\/#website","url":"https:\/\/class.one\/","name":"Class One","description":"Online Learning Platform in Malaysia","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/class.one\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-CN"}]}},"_links":{"self":[{"href":"https:\/\/class.one\/zh-hans\/wp-json\/wp\/v2\/course-tag\/53","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/class.one\/zh-hans\/wp-json\/wp\/v2\/course-tag"}],"about":[{"href":"https:\/\/class.one\/zh-hans\/wp-json\/wp\/v2\/taxonomies\/course-tag"}],"wp:post_type":[{"href":"https:\/\/class.one\/zh-hans\/wp-json\/wp\/v2\/courses?course-tag=53"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}